{"id":119652,"date":"2016-10-31T16:44:10","date_gmt":"2016-10-31T18:44:10","guid":{"rendered":"http:\/\/franciscanos.org.br\/?p=119652"},"modified":"2020-03-20T10:36:56","modified_gmt":"2020-03-20T13:36:56","slug":"religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html","title":{"rendered":"Religiosas de N\u00farsia retornam ao mosteiro para resgatar seu cachorro"},"content":{"rendered":"<p><img loading=\"lazy\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2016\/10\/nursia_311016g.jpg\" alt=\"nursia_311016g\" width=\"830\" height=\"400\" \/><\/p>\n<p><strong>N\u00farsia &#8211;<\/strong> Com capacetes de seguran\u00e7a e acompanhadas por um grupo de bombeiros, duas das irm\u00e3s clarissas de N\u00farsia retornaram nesta manh\u00e3 ao mosteiro \u2013 que resistiu ao terremoto de ontem \u2013 para resgatar seu cachorro Giobbe (em portugu\u00eas J\u00f3, como o personagem da B\u00edblia)<\/p>\n<p>\u201c\u00c9 um cachorro muito paciente com as religiosas\u201d, relatou com afeto a novi\u00e7a L\u00facia \u00e0 imprensa italiana. Junto com Irm\u00e3 Maria Gabriella retornou ao Mosteiro das Clarissas de N\u00farsia\u00a0para recuperar seu animal de estima\u00e7\u00e3o, que n\u00e3o saiu do edif\u00edcio durante o terremoto.<\/p>\n<p>A novi\u00e7a disse \u201cn\u00e3o chegamos a tirar nosso cachorro Giobbe\u201d. Por\u00e9m, gra\u00e7as a ajuda dos bombeiros, elas conseguiram entrar no edif\u00edcio e recuper\u00e1-lo.<\/p>\n<p>Ainda muito assustado e com fome, o cachorro permaneceu sozinho por quase 48 horas. Segundo foi informado, o cachorro foi levado \u00e0 entidade de prote\u00e7\u00e3o animal para ser submetido a alguns exames e, se n\u00e3o houver necessidade de tratamento, Giobbe retornar\u00e1 com as religiosas a outro mosteiro onde elas est\u00e3o alojadas.<\/p>\n<p>A foto foi publicada no Twitter do jornalista Francesco Grignetti (<a href=\"https:\/\/twitter.com\/FGrignetti\">@FGrignetti<\/a>)<br \/>\nCom informa\u00e7\u00f5es do <a href=\"https:\/\/www.aciprensa.com\/noticias\/religiosas-de-nursia-regresan-al-monasterio-para-rescatar-a-su-mascota-81796\/\" target=\"_blank\" rel=\"noopener noreferrer\">ACI\u00a0Prensa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Terremoto na It\u00e1lia<\/p>\n","protected":false},"author":1,"featured_media":217136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Religiosas de N\u00farsia retornam ao mosteiro para resgatar seu cachorro - Not\u00edcias - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Religiosas de N\u00farsia retornam ao mosteiro para resgatar seu cachorro - Not\u00edcias - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"Terremoto na It\u00e1lia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html\" \/>\n<meta property=\"og:site_name\" content=\"Not\u00edcias - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-31T18:44:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-20T13:36:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2016\/10\/nursia_311016g.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"172\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/\",\"name\":\"Not\u00edcias - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2016\/10\/nursia_311016g.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2016\/10\/nursia_311016g.jpg\",\"width\":273,\"height\":172},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html\",\"name\":\"Religiosas de N\u00farsia retornam ao mosteiro para resgatar seu cachorro - Not\u00edcias - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#primaryimage\"},\"datePublished\":\"2016-10-31T18:44:10+00:00\",\"dateModified\":\"2020-03-20T13:36:56+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/noticias\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Religiosas de N\u00farsia retornam ao mosteiro para resgatar seu cachorro\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/noticias\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Religiosas de N\u00farsia retornam ao mosteiro para resgatar seu cachorro - Not\u00edcias - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html","og_locale":"pt_BR","og_type":"article","og_title":"Religiosas de N\u00farsia retornam ao mosteiro para resgatar seu cachorro - Not\u00edcias - Franciscanos","og_description":"Terremoto na It\u00e1lia","og_url":"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html","og_site_name":"Not\u00edcias - Franciscanos","article_published_time":"2016-10-31T18:44:10+00:00","article_modified_time":"2020-03-20T13:36:56+00:00","og_image":[{"width":273,"height":172,"url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2016\/10\/nursia_311016g.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/noticias\/#website","url":"https:\/\/franciscanos.org.br\/noticias\/","name":"Not\u00edcias - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores - OFM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/noticias\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#primaryimage","url":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2016\/10\/nursia_311016g.jpg","contentUrl":"https:\/\/franciscanos.org.br\/noticias\/wp-content\/uploads\/2016\/10\/nursia_311016g.jpg","width":273,"height":172},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#webpage","url":"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html","name":"Religiosas de N\u00farsia retornam ao mosteiro para resgatar seu cachorro - Not\u00edcias - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#primaryimage"},"datePublished":"2016-10-31T18:44:10+00:00","dateModified":"2020-03-20T13:36:56+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/noticias\/religiosas-de-nursia-retornam-ao-mosteiro-para-resgatar-seu-cachorro.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/noticias"},{"@type":"ListItem","position":2,"name":"Religiosas de N\u00farsia retornam ao mosteiro para resgatar seu cachorro"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/b38fbf43118f02820bd932f2e4b14ad3","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/noticias\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/119652"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=119652"}],"version-history":[{"count":1,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/119652\/revisions"}],"predecessor-version":[{"id":222101,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/posts\/119652\/revisions\/222101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media\/217136"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=119652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=119652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=119652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}