{"id":16019,"date":"2012-04-19T07:25:20","date_gmt":"2012-04-19T10:25:20","guid":{"rendered":"http:\/\/new.franciscanos.org.br\/?p=16019"},"modified":"2012-04-19T07:25:20","modified_gmt":"2012-04-19T10:25:20","slug":"quando-os-anos-pesam-e-a-enfermidade-nos-visita","status":"publish","type":"post","link":"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html","title":{"rendered":"Quando os anos pesam e a enfermidade nos visita"},"content":{"rendered":"<h4 style=\"text-align: left;\" align=\"center\"><a href=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2012\/04\/ofs_g19.jpg\"><img loading=\"lazy\" class=\"alignright size-full wp-image-16374\" title=\"Francisco, de Benlliure\" src=\"http:\/\/franciscanos.org.br\/wp-content\/uploads\/2012\/04\/ofs_g19.jpg\" alt=\"\" width=\"400\" height=\"320\" \/><\/a>Refletindo sobre o Servi\u00e7o dos Enfermos e Idosos\u00a0 (SEI) na Ordem Franciscana Secular<\/h4>\n<p><em>E se algum\u00a0 irm\u00e3o cair enfermo, os outros irm\u00e3os devem servi-lo como gostariam de ser servidos<\/em> (Regra Bulada de S\u00e3o Francisco VI, 10).<\/p>\n<p><em>Avan\u00e7ando em idade, aprendam os irm\u00e3os a aceitar a doen\u00e7a e as crescentes dificuldades e a dar \u00e0 vida um sentido mais profundo, no progressivo desprendimento e encaminhamento\u00a0 \u00e0 Terra Prometida <\/em>(CCGG art. 27, 1)<\/p>\n<p style=\"text-align: left;\" align=\"right\"><strong>1.<\/strong> As Fraternidades Franciscanas Seculares sempre tiveram uma preocupa\u00e7\u00e3o toda especial para com os enfermos e os idosos.\u00a0 Houve tempos em que esse segmento da Fraternidade recebia a designa\u00e7\u00e3o, nem sempre bem compreendida, \u00a0de \u201cala paciente\u201d.\u00a0 Hoje designamos de<em> Servi\u00e7o dos Enfermos e Idosos<\/em> (SEI) a essa tarefa de todos os membros de uma Fraternidade no cuidado desses irm\u00e3os que vivem doen\u00e7a e idade avan\u00e7ada. Embora seja de todos tal\u00a0 tarefa \u00e9 confiada de modo particular a um ou mais membros escolhidos ou eleitos para concretizar esse gesto amoroso. Sempre de novo precisamos ficar atentos e inventar expedientes e mimos para que os irm\u00e3os n\u00e3o se sintam esquecidos e nem se considerem marginalizados.<\/p>\n<p style=\"text-align: left;\" align=\"right\"><strong>2.<\/strong> O tema da enfermidade e doen\u00e7a e da idade avan\u00e7ada\u00a0 pode ser visto sob diferentes \u00e2ngulos.\u00a0 H\u00e1 o doente e o idoso de um lado e h\u00e1, de outro, o irm\u00e3o da Fraternidade que \u00e9 encarregado de prestar aten\u00e7\u00e3o na situa\u00e7\u00e3o do irm\u00e3o e da irm\u00e3.\u00a0 Deveremos distinguir o irm\u00e3o doente durante um certo tempo e, de outro, lado aquele que est\u00e1 fadado a n\u00e3o se levantar do leito ou a viver na depend\u00eancia quase que total \u00a0de familiares ou de outras pessoas.\u00a0 Cada situa\u00e7\u00e3o\u00a0 \u00e9 uma situa\u00e7\u00e3o.\u00a0 H\u00e1 doen\u00e7as em que o enfermo conserva sua lucidez e outras em que a fam\u00edlia at\u00e9 chega a poupar visitas para que estas n\u00e3o assistam a espet\u00e1culos constrangedores.<\/p>\n<p style=\"text-align: left;\" align=\"right\"><strong>3.<\/strong> Num primeiro momento fa\u00e7amos algumas considera\u00e7\u00f5es atinentes \u00e0 postura do irm\u00e3o e da irm\u00e3 que precisam ir se\u00a0 retirando da vida ativa e entrando nessa condi\u00e7\u00e3o de\u00a0 idosos ou \u00a0gravemente doentes.<\/p>\n<p style=\"text-align: left;\" align=\"right\">\u2022\u00a0Os documentos franciscanos pedem que o irm\u00e3o acolha a doen\u00e7a e os inconvenientes da idade avan\u00e7ada.\u00a0 As CCGG\u00a0 exortam \u00a0que todos aceitem a situa\u00e7\u00e3o sabendo que nossa exist\u00eancia continuar\u00e1 na vida eterna como \u201ccomunh\u00e3o dos santos\u201d (art. 27,1).<\/p>\n<p style=\"text-align: left;\" align=\"right\">\u2022\u00a0A doen\u00e7a, quando n\u00e3o se manifestar de maneira violenta\u00a0 e n\u00e3o tirando a consci\u00eancia, pode ser uma ocasi\u00e3o de crescimento, de pr\u00e1tica de penit\u00eancia, de aceita\u00e7\u00e3o de nossa limita\u00e7\u00e3o. Idosos e menos idosos somos\u00a0 convidados a aceitar os reveses da vida.\u00a0 Sabemos que \u00e9 f\u00e1cil escrever\u00a0 essa frase,\u00a0 mas\u00a0 que \u00e9 necess\u00e1rio t\u00eampera e garra e muita for\u00e7a do alto para carregar a cruz de uma enfermidade que veio para ficar ou acolher os achaques humilhantes da velhice.<\/p>\n<p>\u2022\u00a0<span style=\"text-align: left;\">Os idosos e enfermos saber\u00e3o ter a simplicidade de comunicar aquilo de que precisam.\u00a0 Num contexto mais centrado no conjunto do tema da fraternidade, \u00a0Francisco fala na Regra\u00a0 Bulada: \u00a0\u201cE onde est\u00e3o e onde quer que se encontrem os irm\u00e3os, mostrem-se mutuamente familiares entre si. E com confian\u00e7a um manifeste um ao outro sua necessidade, porque se uma m\u00e3e ama e nutre seu filho carnal quanto mais diligentemente n\u00e3o deve cada um amar\u00a0 e\u00a0 nutrir seu irm\u00e3o espiritual?\u201d (<\/span><em style=\"text-align: left;\">Regra Bulada\u00a0 VI, 8-9<\/em><span style=\"text-align: left;\">).\u00a0 Assim, o irm\u00e3o doente tem o direito de expor seus desejos\u00a0 sejam eles de coisas simples ( dar um passeio pela cidade, visitar um parente, degustar um sorvete de creme,\u00a0 escutar uma m\u00fasica).<\/span><\/p>\n<p>\u2022 Os doentes e idosos n\u00e3o se acanhem, pois, de exprimirem o que desejam. Por\u00e9m, prestar\u00e3o aten\u00e7\u00e3o para\u00a0 n\u00e3o serem exigentes e procurar\u00e3o evitar reclama\u00e7\u00f5es e \u201cmurmura\u00e7\u00f5es\u201d.<\/p>\n<p>\u2022\u00a0No momento da enfermidade\u00a0 h\u00e1 os que come\u00e7am a refletir sobre sua vida passada e se enchem de escr\u00fapulos e de arrependimentos por atos poucos nobres cometidos.\u00a0 Os acompanhantes\u00a0 (tamb\u00e9m o assistente religioso da Fraternidade) haver\u00e3o de ajudar o irm\u00e3o nesse transe. Que ele possa ter paz no cora\u00e7\u00e3o e n\u00e3o fique remoendo o que passou. Pela confiss\u00e3o sacramental e pelo arrependimento do cora\u00e7\u00e3o saber\u00e1 o doente que foi perdoado.\u00a0 Ningu\u00e9m pode ficar se torturando com escr\u00fapulos e arrependimentos doentios.<\/p>\n<p>\u2022\u00a0Doentes e idosos procurem simplificar as coisas. Na medida do poss\u00edvel esvaziem gavetas, distribuam os bens\u00a0 quando existirem, procurem\u00a0 desligar-se de todas as preocupa\u00e7\u00f5es desnecess\u00e1rias.\u00a0 Joguem-se nas m\u00e3os do Senhor.<\/p>\n<p>\u2022\u00a0Se o idoso e enfermo tiver condi\u00e7\u00f5es de fazer a contribui\u00e7\u00e3o financeira prevista pela Ordem Franciscana Secular haver\u00e1 de realiz\u00e1-lo com presteza.\u00a0 Esse ponto faz parte da forma\u00e7\u00e3o inicial e permanente.\u00a0 H\u00e1 muitos irm\u00e3os e irm\u00e3s acamados que\u00a0 sempre lembram aos familiares e visitas que providenciem o pagamento de sua contribui\u00e7\u00e3o financeira.<\/p>\n<p>\u2022\u00a0Facilitem a vida dos irm\u00e3os da Fraternidade e de sua fam\u00edlia\u00a0 determinando a regularidade com que gostariam de receber os sacramentos\u00a0 da eucaristia e da penit\u00eancia.\u00a0 Conveniente seria que o irm\u00e3o, se dando conta do agravamento da doen\u00e7a, pedisse a visita do sacerdote para receber a un\u00e7\u00e3o dos enfermos.<\/p>\n<p>\u2022\u00a0\u00c0 guisa de sugest\u00e3o diria que o local onde est\u00e1 o enfermo\u00a0 \u00a0fosse \u201cdecorado\u201d\u00a0 com flores e que n\u00e3o se administrasse esse sacramento lugubremente, mas com plena participa\u00e7\u00e3o do enfermo ou idoso e com tintas de alegria e de esperan\u00e7a no fundo do cora\u00e7\u00e3o.\u00a0 Diria mesmo que se cantasse algum hino franciscano.\u00a0 Desta forma, isto \u00e9, com esperan\u00e7a alegre \u00e9 que se prepara a chegada da Irm\u00e3 Morte.<\/p>\n<p>\u2022\u00a0Os irm\u00e3os doentes e\u00a0 idosos, aceitando os inc\u00f4modos da idade as dores do corpo completam em si o que falta \u00e0 paix\u00e3o de Cristo.<\/p>\n<p><strong>4.<\/strong> Vejamos agora alguns cuidados que precisam ter irm\u00e3os e irm\u00e3s encarregados\u00a0 por esse carinhoso servi\u00e7o fraterno. Antes de mais nada deve-se dizer que o cuidado e acompanhamento dos idosos \u00e9 um verdadeiro servi\u00e7o de amor pastoral.\u00a0 Que belo quando irm\u00e3os acompanham os doentes e idosos\u00a0 durante \u00a0a dor e a solid\u00e3o\u00a0 do sofrimento e est\u00e3o presentes, como diletos irm\u00e3os e amigos na celebra\u00e7\u00e3o da passagem. Esses aprenderam a chorar com o que choram e\u00a0 a rir com os que riem.<\/p>\n<p>\u2022\u00a0A visita\u00a0 dever\u00e1\u00a0 se fazer com um certo ritmo. N\u00e3o se pode exagerar na frequ\u00eancia, nem espacej\u00e1-las demais.\u00a0 Tudo dever\u00e1 ser combinado com a fam\u00edlia. O irm\u00e3o visitador precisa sentir o \u201ct\u00f4nus\u201d da fam\u00edlia.\u00a0 Pode ser que alguns familiares nem sempre queiram visitas para que seus entes queridos n\u00e3o se exponham a situa\u00e7\u00f5es constrangedoras (pessoas com incontin\u00eancia etc.).\u00a0 Pode acontecer que a visita precise ser abreviada.\u00a0 Necess\u00e1rio\u00a0 ter sensibilidade para tanto.<\/p>\n<p>\u2022\u00a0O doente e o idoso querem viver, querem sentir uma proximidade carinhosa com que os visita. Num momento em que as esperan\u00e7as humanas v\u00e3o desaparecendo, o enfermo quer uma pessoa realista e que, ao mesmo tempo, \u00a0lhe traga alegria. Sabemos que cada caso \u00e9 um caso.\u00a0 Nunca o doente dever\u00e1 sentir que irm\u00e3o faz uma visita formal ou simplesmente cumprindo a obriga\u00e7\u00e3o de lhe trazer\u00a0 o Sacramento do Corpo do Senhor.<\/p>\n<p>\u2022\u00a0Na administra\u00e7\u00e3o da Comunh\u00e3o eucar\u00edstica, ministro ou irm\u00e3o da Fraternidade cuidar\u00e3o de n\u00e3o se prolongar demais.\u00a0 Bom que o rito fosse desenvolvido com calor na voz e express\u00e3o carinhosa nos gestos. Nada de frio formalismo.<\/p>\n<p>\u2022\u00a0O irm\u00e3o que visita precisa, de alguma forma compreender aquilo que vive o irm\u00e3o, em outras palavras, saber colocar-se em seu lugar. E, como j\u00e1 dissemos, cada caso \u00e9 um caso. H\u00e1\u00a0 os doentes \u00a0mais gravemente enfermos e terminais.\u00a0 H\u00e1 o sofrimento f\u00edsico, \u00a0\u00e9 claro, por vezes aliviado com analg\u00e9sicos, h\u00e1 a vergonha de n\u00e3o poder controlar suas necessidades, o\u00a0 mal-estar de perder o fio de um assunto e ficar num estado de perplexidade. H\u00e1 doentes que passam facilmente de um estado de euforia a outro de depress\u00e3o e de pranto. N\u00e3o se deve ficar chocado quando um irm\u00e3o se revolta contra a doen\u00e7a e a proximidade da morte\u00a0 por meio de palavras e mesmo de vocifera\u00e7\u00f5es.\u00a0 Deitado em seu leito, o doente pode estar vivendo sentimentos de c\u00f3lera, de depress\u00e3o, de revolta com a chegada da morte, de d\u00favidas a respeito de sua salva\u00e7\u00e3o eterna, de remorsos cru\u00e9is e mesmo crises de desespero.\u00a0 Por vezes pode mesmo acontecer que os doentes manifestem sua revolta contra Deus.\u00a0 O visitador n\u00e3o far\u00e1 discursos moralizantes, mas tentar\u00e1 ouvir e mais vale ficar quieto e perto do que fazer discursos para defender\u00a0 o Senhor Deus. Que o irm\u00e3o doente chore, reclame e encontre em nosso rosto a paz da compreens\u00e3o.<\/p>\n<p>\u2022\u00a0O irm\u00e3o respons\u00e1vel pelo servi\u00e7o dos idosos e enfermos saber\u00e1\u00a0 satisfazer seus desejos e suas necessidades espirituais.\u00a0 O doente precisa sentir que continua dono de sua hist\u00f3ria. N\u00e3o \u00e9 pelo fato de estar numa cama ou impossibilitado de caminhar que pode delegar a outros os fios de sua hist\u00f3ria.\u00a0 Sobretudo quando a doen\u00e7a \u00e9 grave o doente sente um peso enorme sobre ele e precisa ser ajudado, discreta, mas realmente ajudado. H\u00e1 muitas perguntas que ele se faz interiormente sem exprimi-las em palavras. O doente sente que o corpo\u00a0 n\u00e3o responde mais e que a mente se esvai. H\u00e1 tamb\u00e9m essa\u00a0 quest\u00e3o de todos, tamb\u00e9m dos crist\u00e3os, tamb\u00e9m dos franciscanos\u00a0 religiosos e seculares,\u00a0 a respeito depois da morte. Cremos na vida que vem depois da morte, mas&#8230; Os que n\u00e3o tem f\u00e9 esclarecida pesam: \u201cO que me vai acontecer agora? Vou bater com a cabe\u00e7a num\u00a0 muro de pedra?\u00a0\u00a0 As CCGG da OFS lembram aos doentes:\u00a0 \u201cEstejam firmemente convencidos de que a comunidade dos crentes em Cristo e dos que se amam nele prosseguir\u00e1 na vida eterna como comunh\u00e3o dos santos.\u00a0 Os franciscanos seculares se empenhem em criar em seu ambiente, sobretudo nas Fraternidades, uma clima de f\u00e9 e de esperan\u00e7a, de modo que a \u201cirm\u00e3 morte\u201d, seja vista\u00a0 como passagem para o Pai e todos possam preparar-se para ela com serenidade\u201d (art. 27,1-2).<\/p>\n<p>\u2022\u00a0Muitas Fraternidades costumam organizar encontros festivos e alegres, de modo especial\u00a0 por ocasi\u00e3o das festas do Natal, da P\u00e1scoa e nas comemora\u00e7\u00f5es franciscanas para os quais s\u00e3o convidados os irm\u00e3os que ainda podem se locomover.\u00a0 Essas reuni\u00f5es feitas num espa\u00e7o de beleza, de alegria, de f\u00e9 s\u00e3o de grande proveito para os irm\u00e3os.\u00a0 A experi\u00eancia diz que,\u00a0 mormente para aqueles que nunca podem sair de casa,\u00a0 que a data de seu anivers\u00e1rio seja belamente lembrada e festejada\u00a0 desde a manh\u00e3 com mensagem, presentes, visita e bolo com velas.<\/p>\n<p><strong>5.<\/strong> Procurem os irm\u00e3os que cuidam dos idosos e doentes se fazerem presentes no sepultamento e tamb\u00e9m junto da fam\u00edlia\u00a0 do falecido.\u00a0 Sempre haver\u00e3o de estar\u00a0 com discri\u00e7\u00e3o,\u00a0 mas sempre como irm\u00e3os verdadeiros sofrem com a partida do irm\u00e3o.<\/p>\n<h5>\u00a0<strong>Ap\u00eandice\u00a0 1<\/strong><\/h5>\n<h5><strong>\u00a0<\/strong>(para ajudar os que visitam enfermos e idosos)<\/h5>\n<p><strong>Quando se envelhece&#8230;<\/strong><\/p>\n<p><strong>&#8230;luzes e sombras<\/strong><\/p>\n<p>Quantas coisas atravessam a cabe\u00e7a dos idosos e doentes:<\/p>\n<ul>\n<li>H\u00e1 a alegria do dever cumprido, \u00a0da miss\u00e3o realizada: um pai e uma m\u00e3e olham os filhos crescidos, adultos, j\u00e1 tamb\u00e9m pais e av\u00f3s, um sacerdote faz desfilar em sua mente os anos de minist\u00e9rio, uma professora se recorda das turmas e dos alunos que foram objeto de seus cuidados.\u00a0 H\u00e1 essa alegria de experimentar o sabor dos frutos que foram lentamente amadurecendo.<\/li>\n<li>H\u00e1 essa sensa\u00e7\u00e3o de que outros est\u00e3o chegando e v\u00e3o ocupando um espa\u00e7o que era o nosso.\u00a0 H\u00e1 esse pressentimento de que se est\u00e1 sobrando.<\/li>\n<li>H\u00e1 essa experi\u00eancia de anos e anos no campo profissional, nas atividades da par\u00f3quia,\u00a0 na Fraternidade franciscana, no contato humano, na arte de negociar, no exerc\u00edcio da acolhida do diferente. Os idosos s\u00e3o peritos em humanidade.\u00a0 S\u00e3o s\u00e1bios que precisam fazer ouvir a voz de sua sabedoria.<\/li>\n<li>H\u00e1 essa sensa\u00e7\u00e3o de cansa\u00e7o das pernas e dos bra\u00e7os, o enfraquecimento da mem\u00f3ria, a respira\u00e7\u00e3o meio ofegante, o sono diante do computador, da televis\u00e3o e numa sala de espera de um consult\u00f3rio m\u00e9dico.<\/li>\n<li>H\u00e1 essa alegria de poder ir refazendo sua biografia\u00a0 humana atrav\u00e9s do tempo que Deus permitiu que se fosse vivendo.<\/li>\n<li>Na medida em que os anos chegam vem essa impress\u00e3o que as cortinas est\u00e3o para ser puxadas, que h\u00e1 pouco que fazer.\u00a0 Os que ganham idade se d\u00e3o conta de limita\u00e7\u00f5es irrevers\u00edveis. Ser\u00e1 que ainda se pode fazer algum projeto?\u00a0 Quais?<\/li>\n<li>A velhice \u00e9 tempo em que se aprende e se vive o despojamento. Nem sempre \u00e9 pedido o parecer do idoso. Ou ent\u00e3o nem \u00e9 mesmo levado em considera\u00e7\u00e3o. \u00a0\u00a0Os m\u00f3veis e os h\u00e1bitos s\u00e3o mudados de lugar sem o parecer do idoso ou do doente. H\u00e1 uma sensa\u00e7\u00e3o de inutilidade, de se ser um traste tolerado.<\/li>\n<li>Quando se envelhece h\u00e1 mais tempo para ler, para ver as plantas crescendo, para ver se os passarinhos j\u00e1 nasceram no ninho feito na goiabeira, tempo de acolher com clama uma visita.\u00a0 O idoso n\u00e3o \u00e9 um apressado. Normalmente transmite paz e serenidade.<\/li>\n<li>H\u00e1 esses idosos e anci\u00e3os descuidados, sujos, lambuzados, vestindo roupa velha, rasgada.\u00a0 H\u00e1 esses velhos nos asilos, nos abrigos, nas marquises que s\u00e3o verdadeiros restos humanos.<\/li>\n<li>H\u00e1 esses idosos que evitam conversar\u00a0 porque sua exist\u00eancia\u00a0 n\u00e3o teve frutos saborosos e t\u00eam receio de se exporem \u00e0 piedade alheia.<\/li>\n<li>H\u00e1 doentes e idosos que t\u00eam sempre um sorriso de paz, que ajudam a descascar ma\u00e7as para a torta da noite, ou aqueles que ainda fazem a contabilidade da capela do bairro. Enfeitam o mundo com sua hist\u00f3ria.\u00a0 H\u00e1 esses que oferecem para passar uma roupa, h\u00e1 os que falam de flores e aqueles que s\u00f3 dissertam sobre as dores.<\/li>\n<li>H\u00e1 os que sabem que, na hora do trespasse, os anjos chegar\u00e3o\u00a0 para lhes dar a m\u00e3o. Outros t\u00eam medo de colocar os p\u00e9s nessa terra desconhecida.\u00a0 H\u00e1 os que rezam com toda confian\u00e7a: \u201cSanta Maria, rogai por n\u00f3s, agora e na hora de nossa morte&#8230;\u201d<\/li>\n<li>\u201cQualquer que seja a sua idade, guardem este pensamento:\u00a0 o importante n\u00e3o \u00e9 viver muito ou pouco, mas realizar na vida o plano para o qual Deus nos criou.\u00a0 As rosas, a rigor, vivem um dia. Mas vivem plenamente porque realizam o destino de gra\u00e7a e de beleza que trazem \u00e0 terra. Se voc\u00eas sentirem\u00a0 que os anos passam e a mocidade se vai, pe\u00e7am a Deus para si e para os que se tornam menos jovens\u00a0 a gra\u00e7a de, envelhecendo, n\u00e3o azedar, n\u00e3o virar vinagre\u201d\u00a0 (Dom Helder C\u00e2mara).<\/li>\n<\/ul>\n<h5>\u00a0<strong>Ap\u00eandice\u00a0 2<\/strong><\/h5>\n<p><strong>Os desejos de S\u00e3o Francisco quando estava doente&#8230;.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><em>Os que\u00a0 s\u00e3o respons\u00e1veis pelo\u00a0 Servi\u00e7o dos Enfermos e Idosos\u00a0 em nossas\u00a0 Fraternidades\u00a0 OFS saber\u00e3o alegrar os irm\u00e3os enfraquecidos.\u00a0 Procurar\u00e3o satisfazer seus l\u00edcitos desejos:\u00a0 procurar-lhes uma fruta que \u00a0apreciam, dar\u00a0 um \u201cgiro\u201d de carro \u00a0pela cidade,\u00a0 fazer com que eles encontrem seu amigos.\u00a0 Os bi\u00f3grafos de\u00a0 S\u00e3o Francisco\u00a0 relatam alguns desejos, pelo menos curiosos, expressos pelo santo j\u00e1 bem perto da morte e quando j\u00e1 havia atingido alt\u00edssimo grau de santidade.\u00a0 Andr\u00e9 Menard, frade menor franc\u00eas,\u00a0 escreve a respeito de tr\u00eas deles: m\u00fasica ao som da c\u00edtara, uma por\u00e7\u00e3o de aipo, uma torta de am\u00eandoas que\u00a0 Fra Jacoba sabia fazer (Les envies, les humeurs et les variations de Fran\u00e7ois, in \u00c9vangile Aujourd\u2019hui, n.147. agosto de 1990, p. 42-46).<\/em><\/p>\n<p><em><\/em>Um pequeno grupo de irm\u00e3os rodeia Francisco no final de sua vida. Permanecem bem perto do santo pai e demonstram aten\u00e7\u00e3o e solicitude.\u00a0 O testemunho deles nos permite chegar at\u00e9 a mais profunda humanidade de Francisco.\u00a0 Deixando de lado o \u201cn\u00e3o fica bem\u201d ou \u201co que os outros v\u00e3o pensar\u201d, Francisco d\u00e1 livre curso \u00e0 realiza\u00e7\u00e3o de seus justos desejos.<\/p>\n<p><strong>Um pouco de m\u00fasica\u00a0 <\/strong>&#8211;\u00a0 Prostrado por muitas enfermidades, Francisco sentiu o desejo de ouvir um pouco de m\u00fasica que viesse a lhe devolver a alegria espiritual (<em>cf. Legenda Maior de S\u00e3o Boaventura\u00a0 5, 11)<\/em>.\u00a0 Francisco sabia que esse expediente lhe faria bem. \u201cEmbora muito enfraquecido pela doen\u00e7a, o santo, para consolo de seu esp\u00edrito e para n\u00e3o se deixar abater no meio de graves e numerosas enfermidades, \u00a0mandava cantar repetidas vezes durante o dia os <em>Louvores de Deus<\/em> que havia composto, tempos atr\u00e1s, durante um per\u00edodo de doen\u00e7a. Pedia tamb\u00e9m que os cantassem durante a noite para edifica\u00e7\u00e3o e para recreio daqueles que por sua causa estavam em vig\u00edlia no pal\u00e1cio (do bispo em Assis) (<em>Legenda Perusina,64<\/em>).<\/p>\n<p>Seu desejo encontrava uma certa resist\u00eancia\u00a0 \u00e0 sua volta. Um dos frades que havia sido conhecido como o\u00a0 rei dos poetas n\u00e3o aceitava realizar o desejo de Francisco.<\/p>\n<p>\u201cDisse Francisco a um de seus irm\u00e3os que no\u00a0 s\u00e9culo era tocador de c\u00edtara: \u00a0\u2018Irm\u00e3o&#8230; gostaria que fosses em segredo pedir a uma pessoa honesta uma c\u00edtara emprestada, na qual me tocasses uma bela m\u00fasica para acompanhar as ora\u00e7\u00f5es e os Louvores do Senhor&#8230;\u2019\u00a0 O irm\u00e3o\u00a0 respondeu-lhe:\u00a0 \u2018Pai, tenho vergonha de ir \u00e0 procura deste instrumento. Os habitantes desta cidade sabem que, no mundo, eu fui tocador de c\u00edtara; e tenho receio de os escandalizar, fazendo com que pensem que estou voltando ao meu of\u00edcio&#8230;\u2019\u201d\u00a0 (<em>Legenda Perusina, 24<\/em>).<\/p>\n<p>Francisco bem podia ter previsto esta dificuldade. Ele mesmo, anteriormente, havia dito que os instrumentos de m\u00fasica que antigamente serviam aos santos\u00a0 para o louvor de Deus, agora serviam \u00e0 vaidade e ao pecado,\u00a0 contrariamente \u00e0 vontade de Deus\u201d.<\/p>\n<p>Francisco respeita a delicadeza de consci\u00eancia do irm\u00e3o musico: \u201cEst\u00e1 bem, irm\u00e3o, n\u00e3o se fala mais nisso\u201d.\u00a0 O Senhor, no entanto, haveria de atender de outra maneira, o desejo de seu servo:\u00a0 \u201cNa noite seguinte&#8230; Francisco come\u00e7ou a ouvir perto de casa, a mais bela e mais suave melodia, que at\u00e9 ent\u00e3o ouvira, nas cordas de uma c\u00edtara&#8230; e, de manh\u00e3, disse ao companheiro:\u00a0 \u2018Irm\u00e3o, pedi-te e n\u00e3o me atendeste;\u00a0 mas o Senhor, que consola os seus amigos em suas tribula\u00e7\u00f5es, dignou-se consolar-me esta noite\u2019\u201d (<em>Legenda Perusina, 24<\/em>).<\/p>\n<p>Encorajado por esta aprova\u00e7\u00e3o divina, Francisco\u00a0 p\u00f4de encontrar resposta a dar a Frei Elias. Na verdade, o Ministro Geral\u00a0 exprimiu assim sua pr\u00f3pria perplexidade ao relatar as rea\u00e7\u00f5es dos habitantes de Assis:\u00a0 \u201cComo se explica tanta alegria quando se aproxima a hora da morte?\u00a0 N\u00e3o seria melhor que pensasse na morte?\u201d\u00a0 Francisco n\u00e3o hesita em retrucar: \u201cDeixa-me rejubilar no Senhor e cantar os seus louvores em meio \u00e0s minhas enfermidades: pela gra\u00e7a do Esp\u00edrito estou t\u00e3o unido ao meu Senhor que,\u00a0 por sua bondade, posso na verdade regozijar-me no Alt\u00edssimo\u201d (<em>Legenda Perusina\u00a0 64<\/em>).<\/p>\n<p>Atrav\u00e9s de sua liberdade de comportamento Francisco sugere que o caminho que ele seguiu ontem continua vi\u00e1vel hoje.\u00a0 Tudo \u00e9 puro para os puros e tudo \u00e9 santo para os santos. Os instrumentos de m\u00fasica, c\u00edtaras, salt\u00e9rios e outros podem se prestar para o louvor de Deus e a consola\u00e7\u00e3o da alma. Trata-se do bom uso a se fazer da m\u00fasica.<\/p>\n<p><strong>\u00a0<\/strong><strong>Um\u00a0 pouco de aipo <\/strong>\u00a0&#8211;\u00a0 Francisco jaz em seu leito, muito enfraquecido pela enfermidade. Procura algum reconforto. Teve desejo de comer aipo. Era noite e o tempo se apresentava inclemente.\u00a0 Sabe ele muito bem que aquele n\u00e3o era o melhor momento de exprimir um tal desejo. E al\u00e9m disso o irm\u00e3o da cozinha parece\u00a0 n\u00e3o querer colaborar. Ele apresenta argumentos s\u00f3lidos que tornavam invi\u00e1vel a satisfa\u00e7\u00e3o desse desejo naquela hora. Francisco vai insistir para que o irm\u00e3o se decida a acolher seu pedido, embora sem muita convic\u00e7\u00e3o. Como o irm\u00e3o cozinheiro haveria de se\u00a0 ver livre desse doente caprichoso, febril e teimoso?<\/p>\n<p>Os c\u00e9us haveriam novamente de dar raz\u00e3o a Francisco. No meio de uma soca de ervas sem valor, l\u00e1 se acha um pouquinho de aipo. Francisco provar\u00e1 um pouco e se sentir\u00e1 reconfortado. N\u00e3o poder\u00e1 ele, no entanto, deixar de exprimir a leve decep\u00e7\u00e3o de algu\u00e9m\u00a0 que tem que insistir muito para ser ouvido. Desta forma nos \u00e9 revelado que, mesmo sendo j\u00e1 objeto de venera\u00e7\u00e3o, Francisco faz a experi\u00eancia da depend\u00eancia que o coloca\u00a0 \u00e0 merc\u00ea dos outros. Ele o exprime sem azedume, at\u00e9 mesmo com do\u00e7ura, como que desejando despertar a generosidade meio adormecida de seus companheiros:\u00a0 \u201cIrm\u00e3os, cumpri as ordens sempre\u00a0 \u00e0 primeira palavra, sem esperar que sejam repetidas\u201d\u00a0 (<em>2Celano 51<\/em>).<\/p>\n<p><strong>Um peda\u00e7o de torta de am\u00eandoas<\/strong>\u00a0 &#8211; \u00a0Teria\u00a0 Frei Elias raz\u00e3o em achar nosso moribundo meio \u201csem ju\u00edzo\u201d? Mas Francisco se encontra\u00a0 com pleno uso de suas faculdades, mormente da intelig\u00eancia e do cora\u00e7\u00e3o. Disse Francisco a Elias:\u00a0 \u201cCreio que se inform\u00e1sseis a Senhora Jacoba de Settesoli a respeito de meu estado de sa\u00fade, haver\u00edeis de lhe propiciar ocasi\u00e3o de uma gesto de delicadeza e de consola\u00e7\u00e3o\u201d. Francisco est\u00e1 disposto de dar a Fra Jacoba o prazer de v\u00ea-lo,\u00a0 saboreando pela \u00faltima vez os doces que ela sabia t\u00e3o bem fazer. \u201cQue ela mande\u00a0 tamb\u00e9m aquele doce que tantas vezes fez para mim quando eu estive em Roma\u201d.<\/p>\n<p>Francisco tinha bom gosto. Queria um \u201cmostacciulo\u201d, uma torta feita com am\u00eandoas, a\u00e7\u00facar e outros ingredientes\u00a0 (<em>Legenda Perusina\u00a0 101<\/em>).<\/p>\n<p>Um vez\u00a0 mais \u00a0Francisco v\u00ea seu desejo atendido. Fra Jacoba antecipa a realiza\u00e7\u00e3o de seu querer. Ela conhece os gostos de seu amigo e lhe traz a torta de am\u00eandoas. A acolhida de Francisco \u00e9 toda espontaneidade, verdadeira liberdade de amor:\u00a0 \u201cBendito seja Deus que nos enviou nosso irm\u00e3o, Senhora Jacoba! Abri as portas e fazei com que ela entre, pois o artigo que pro\u00edbe a entrada de mulheres n\u00e3o vale para\u00a0 Fra Jacoba (<em>3Celano 37<\/em>).<\/p>\n<p>E Jacoba \u201ctinha\u00a0 preparado para o santo\u00a0 Pai os doces que ele queria&#8230; Ele mal os provou porque as for\u00e7as do corpo iam declinando&#8230;\u201d (Legenda Perusina, 101). Francisco ainda se lembrou que Frei Bernardo tamb\u00e9m apreciava esse doce: \u201cNo dia em que a Senhora Jacoba fez aqueles doces para o bem-aventurado Francisco, lembrou-se ele de Frei Bernardo\u00a0 dizendo: \u2018Frei Bernardo \u00e9 que deve gostar desse doce\u201d. E mandou a um companheiro que o chamasse: \u2018Vai, e dize a Frei Bernardo que venha c\u00e1\u2019\u201d (<em>Legenda Perusina, 107<\/em>).<\/p>\n<p><strong>Frei Almir Ribeiro Guimar\u00e3es, OFM<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OFS<\/p>\n","protected":false},"author":1,"featured_media":174765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[50],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quando os anos pesam e a enfermidade nos visita - Carisma - Franciscanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando os anos pesam e a enfermidade nos visita - Carisma - Franciscanos\" \/>\n<meta property=\"og:description\" content=\"OFS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html\" \/>\n<meta property=\"og:site_name\" content=\"Carisma - Franciscanos\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-19T10:25:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscanos.org.br\/carisma\/wp-content\/uploads\/2018\/10\/ofs_g19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/#website\",\"url\":\"https:\/\/franciscanos.org.br\/carisma\/\",\"name\":\"Carisma - Franciscanos\",\"description\":\"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/franciscanos.org.br\/carisma\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#primaryimage\",\"url\":\"https:\/\/franciscanos.org.br\/carisma\/wp-content\/uploads\/2018\/10\/ofs_g19.jpg\",\"contentUrl\":\"https:\/\/franciscanos.org.br\/carisma\/wp-content\/uploads\/2018\/10\/ofs_g19.jpg\",\"width\":400,\"height\":320},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#webpage\",\"url\":\"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html\",\"name\":\"Quando os anos pesam e a enfermidade nos visita - Carisma - Franciscanos\",\"isPartOf\":{\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#primaryimage\"},\"datePublished\":\"2012-04-19T10:25:20+00:00\",\"dateModified\":\"2012-04-19T10:25:20+00:00\",\"author\":{\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/#\/schema\/person\/e352342a457f086dc6152f9c73a3d093\"},\"breadcrumb\":{\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/franciscanos.org.br\/carisma\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quando os anos pesam e a enfermidade nos visita\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/#\/schema\/person\/e352342a457f086dc6152f9c73a3d093\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/franciscanos.org.br\/carisma\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/franciscanos.org.br\/carisma\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quando os anos pesam e a enfermidade nos visita - Carisma - Franciscanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html","og_locale":"pt_BR","og_type":"article","og_title":"Quando os anos pesam e a enfermidade nos visita - Carisma - Franciscanos","og_description":"OFS","og_url":"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html","og_site_name":"Carisma - Franciscanos","article_published_time":"2012-04-19T10:25:20+00:00","og_image":[{"width":400,"height":320,"url":"https:\/\/franciscanos.org.br\/carisma\/wp-content\/uploads\/2018\/10\/ofs_g19.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/franciscanos.org.br\/carisma\/#website","url":"https:\/\/franciscanos.org.br\/carisma\/","name":"Carisma - Franciscanos","description":"Prov\u00edncia Franciscana da Imaculada Concei\u00e7\u00e3o do Brasil - Ordem dos Frades Menores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscanos.org.br\/carisma\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#primaryimage","url":"https:\/\/franciscanos.org.br\/carisma\/wp-content\/uploads\/2018\/10\/ofs_g19.jpg","contentUrl":"https:\/\/franciscanos.org.br\/carisma\/wp-content\/uploads\/2018\/10\/ofs_g19.jpg","width":400,"height":320},{"@type":"WebPage","@id":"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#webpage","url":"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html","name":"Quando os anos pesam e a enfermidade nos visita - Carisma - Franciscanos","isPartOf":{"@id":"https:\/\/franciscanos.org.br\/carisma\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#primaryimage"},"datePublished":"2012-04-19T10:25:20+00:00","dateModified":"2012-04-19T10:25:20+00:00","author":{"@id":"https:\/\/franciscanos.org.br\/carisma\/#\/schema\/person\/e352342a457f086dc6152f9c73a3d093"},"breadcrumb":{"@id":"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franciscanos.org.br\/carisma\/quando-os-anos-pesam-e-a-enfermidade-nos-visita.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscanos.org.br\/carisma"},{"@type":"ListItem","position":2,"name":"Quando os anos pesam e a enfermidade nos visita"}]},{"@type":"Person","@id":"https:\/\/franciscanos.org.br\/carisma\/#\/schema\/person\/e352342a457f086dc6152f9c73a3d093","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/franciscanos.org.br\/carisma\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8495742d34d0ba6448ea1c628263b3e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/franciscanos.org.br\/carisma\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/posts\/16019"}],"collection":[{"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/comments?post=16019"}],"version-history":[{"count":0,"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/posts\/16019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/media\/174765"}],"wp:attachment":[{"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/media?parent=16019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/categories?post=16019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscanos.org.br\/carisma\/wp-json\/wp\/v2\/tags?post=16019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}